{"id":38,"count":29,"description":"","link":"https:\/\/www.gruppoghedini.it\/usato\/modello\/renegade\/","name":"Renegade","slug":"renegade","taxonomy":"veicoli_modello","parent":22,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gruppoghedini.it\/usato\/wp-json\/wp\/v2\/veicoli_modello\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruppoghedini.it\/usato\/wp-json\/wp\/v2\/veicoli_modello"}],"about":[{"href":"https:\/\/www.gruppoghedini.it\/usato\/wp-json\/wp\/v2\/taxonomies\/veicoli_modello"}],"up":[{"embeddable":true,"href":"https:\/\/www.gruppoghedini.it\/usato\/wp-json\/wp\/v2\/veicoli_modello\/22"}],"wp:post_type":[{"href":"https:\/\/www.gruppoghedini.it\/usato\/wp-json\/wp\/v2\/veicoli?veicoli_modello=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}